{"id":12949,"date":"2020-07-08T09:04:50","date_gmt":"2020-07-08T12:04:50","guid":{"rendered":"http:\/\/blog.me.com.br\/?p=12949"},"modified":"2021-08-12T07:30:14","modified_gmt":"2021-08-12T10:30:14","slug":"mercado-eletronico-entrevista-sobre-digitalizacao-em-compras","status":"publish","type":"post","link":"https:\/\/blog.me.com.br\/pt\/mercado-eletronico-entrevista-sobre-digitalizacao-em-compras\/","title":{"rendered":"Mercado Eletr\u00f4nico participa em entrevista sobre digitaliza\u00e7\u00e3o dos pedidos de compras B2B"},"content":{"rendered":"<div class=\"article-header\">\n<div class=\"epyt-video-wrapper\"><iframe loading=\"lazy\"  id=\"_ytid_74629\"  width=\"1200\" height=\"675\"  data-origwidth=\"1200\" data-origheight=\"675\" src=\"https:\/\/www.youtube.com\/embed\/Ed8xoC9O9WE?enablejsapi=1&#038;autoplay=0&#038;cc_load_policy=0&#038;cc_lang_pref=&#038;iv_load_policy=1&#038;loop=0&#038;rel=0&#038;fs=1&#038;playsinline=0&#038;autohide=2&#038;theme=dark&#038;color=red&#038;controls=1&#038;disablekb=0&#038;\" class=\"__youtube_prefs__  epyt-is-override  no-lazyload\" title=\"PapoF\u00e1cil #519 Mercado Eletr\u00f4nico automa\u00e7\u00e3o de processo de compras B2B em um amplo marketplace\"  allow=\"fullscreen; accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen data-no-lazy=\"1\" data-skipgform_ajax_framebjll=\"\"><\/iframe><\/div>\n<p>&nbsp;<\/p>\n<p>Andr\u00e9 Kerbauy, Diretor de Consultoria SaaS do Mercado Eletr\u00f4nico, participou numa entrevista exclusiva com o jornalista Flavio Xand\u00f3. A conversa foi para o ar no dia 28 de junho de 2020 e abordou, de forma descontra\u00edda e direta, como \u00e9 que as empresas podem automatizar os seus processos de pedidos de compras B2B.<\/p>\n<p>Andr\u00e9 teve a oportunidade de falar sobre a solu\u00e7\u00e3o Order Management, que proporciona, de forma simples e r\u00e1pida, um primeiro passo para a transforma\u00e7\u00e3o digital da \u00e1rea de abastecimentos.<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Automa\u00e7\u00e3o dos pedidos de compras B2B<\/strong><\/h2>\n<\/div>\n<h3>Quem \u00e9 o Mercado Eletr\u00f4nico?<\/h3>\n<p>O Mercado Eletr\u00f4nico \u00e9 l\u00edder na Am\u00e9rica Latina em solu\u00e7\u00f5es de com\u00e9rcio eletr\u00f3nico B2B. As suas tecnologias e servi\u00e7os para as \u00e1reas de compras ajudam empresas a conquistar mais economia, agilidade, governan\u00e7a e colabora\u00e7\u00e3o.<\/p>\n<p>As solu\u00e7\u00f5es B2B est\u00e3o fundamentadas em usabilidade, cloud computing, intelig\u00eancia artificial e ecossistemas que fazem parte dos processos de compras, numa plataforma com op\u00e7\u00f5es SaaS e PaaS, que possibilita a integra\u00e7\u00e3o com qualquer ERP.<\/p>\n<p>Com escrit\u00f3rios no Brasil, Portugal, M\u00e9xico e Estados Unidos, contabiliza mais de 1 milh\u00e3o de fornecedores, 8 mil compradores e transaciona \u20ac15 mil milh\u00f5es em neg\u00f3cios entre fornecedores e compradores.<\/p>\n<p><a href=\"https:\/\/blog.me.com.br\/pt\/voce-conhece-as-solucoes-b2b-do-me\/\">Clique aqui <\/a>para saber mais.<\/p>\n<h3>Order Management como facilitador da gest\u00e3o de compras<\/h3>\n<p>Atrav\u00e9s da solu\u00e7\u00e3o, os profissionais de compras podem automatizar toda a gest\u00e3o do ciclo de pedidos, desde o envio para o fornecedor at\u00e9 \u00e0 rece\u00e7\u00e3o da mercadoria. A automa\u00e7\u00e3o dos processos \u00e9 realizada de forma simples e r\u00e1pida, garantindo mais seguran\u00e7a, agilidade, economia e colabora\u00e7\u00e3o entre os envolvidos na cadeia de fornecimento. Entre as pr\u00e1ticas da solu\u00e7\u00e3o est\u00e3o \u201cRegulariza\u00e7\u00e3o e Aprova\u00e7\u00e3o de Pedidos\u201d, \u201cConfirma\u00e7\u00e3o e Tratamento\u201d, \u201cRece\u00e7\u00e3o de Produtos e Servi\u00e7os\u201d, e \u201cSpend Analysis\u201d.<\/p>\n<p>Entre os benef\u00edcios comuns para ambas as partes est\u00e3o: automatizar processos com transpar\u00eancia e seguran\u00e7a, estreitar as parcerias de neg\u00f3cios, reduzir custos e melhorar a comunica\u00e7\u00e3o entre as empresas.<\/p>\n<p>&nbsp;<\/p>\n<h3>Gest\u00e3o de pedidos sem custos para o comprador<\/h3>\n<div>\n<p>Quem teme a digitaliza\u00e7\u00e3o teme, acima de tudo, a press\u00e3o do tempo e dos altos investimentos. Mas, diferentemente do que muitos pensam, a transforma\u00e7\u00e3o digital da \u00e1rea de compras pode come\u00e7ar aos poucos e de forma escal\u00e1vel.<\/p>\n<p>O Order Management pode ser o primeiro passo para esta transi\u00e7\u00e3o. Com investimento zero e r\u00e1pida implementa\u00e7\u00e3o para empresas compradoras, \u00e9 poss\u00edvel ter uma ferramenta que promova redu\u00e7\u00e3o de custos e de processos operacionais, controlo e parcerias mais estreitas na cadeia de abastecimento.<\/p>\n<p>&nbsp;<\/p>\n<p>Assista \u00e0 entrevista na \u00edntegra para entender melhor cada um dos <em>insights<\/em> abordados acima.<\/p>\n<p>Aproveite e assine a nossa <a href=\"https:\/\/content.mercadoe.com\/pt-pt\/newsletter-do-mercado-eletronico\">newsletter<\/a> para ficar por dentro de tudo o que acontece no mercado B2B!<\/p>\n<p>At\u00e9 \u00e0 pr\u00f3xima!<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>&nbsp; Andr\u00e9 Kerbauy, Diretor de Consultoria SaaS do Mercado Eletr\u00f4nico, participou numa entrevista exclusiva com o jornalista Flavio Xand\u00f3. A conversa foi para o ar no dia 28 de junho de 2020 e abordou, de forma descontra\u00edda e direta, como \u00e9 que as empresas podem automatizar os seus processos de pedidos de compras B2B. Andr\u00e9 &#8230; <\/p>\n","protected":false},"author":1,"featured_media":6816,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","om_disable_all_campaigns":false,"footnotes":""},"categories":[4467,27],"tags":[8039,56,97,102],"acf":[],"_links":{"self":[{"href":"https:\/\/blog.me.com.br\/pt\/wp-json\/wp\/v2\/posts\/12949"}],"collection":[{"href":"https:\/\/blog.me.com.br\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.me.com.br\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.me.com.br\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.me.com.br\/pt\/wp-json\/wp\/v2\/comments?post=12949"}],"version-history":[{"count":1,"href":"https:\/\/blog.me.com.br\/pt\/wp-json\/wp\/v2\/posts\/12949\/revisions"}],"predecessor-version":[{"id":14863,"href":"https:\/\/blog.me.com.br\/pt\/wp-json\/wp\/v2\/posts\/12949\/revisions\/14863"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.me.com.br\/pt\/wp-json\/wp\/v2\/media\/6816"}],"wp:attachment":[{"href":"https:\/\/blog.me.com.br\/pt\/wp-json\/wp\/v2\/media?parent=12949"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.me.com.br\/pt\/wp-json\/wp\/v2\/categories?post=12949"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.me.com.br\/pt\/wp-json\/wp\/v2\/tags?post=12949"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}